{"id":2309,"date":"2023-04-10T17:33:56","date_gmt":"2023-04-10T12:03:56","guid":{"rendered":"https:\/\/blog.fun88inr.com\/te\/?p=2309"},"modified":"2023-04-10T17:33:56","modified_gmt":"2023-04-10T12:03:56","slug":"dc-vs-mi-prediction-2023-in-telugu","status":"publish","type":"post","link":"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/","title":{"rendered":"DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 : \u0c10\u0c2a\u0c3f\u0c0e\u0c32\u0c4d 16\u0c35 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d \u0c2a\u0c4d\u0c30\u0c3f\u0c35\u0c4d\u0c2f\u0c42"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_51_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-64e3ccdcef7c8\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-64e3ccdcef7c8\"  type=\"checkbox\" id=\"item-64e3ccdcef7c8\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-visibility-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E2%80%93_%E0%B0%AE%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9A%E0%B1%8D_%E0%B0%B5%E0%B0%BF%E0%B0%B5%E0%B0%B0%E0%B0%BE%E0%B0%B2%E0%B1%81\" title=\"DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 &#8211; \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d \u0c35\u0c3f\u0c35\u0c30\u0c3e\u0c32\u0c41:\">DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 &#8211; \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d \u0c35\u0c3f\u0c35\u0c30\u0c3e\u0c32\u0c41:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_2023_%E0%B0%AE%E0%B1%82%E0%B0%A1%E0%B1%81_%E0%B0%AE%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9A%E0%B1%8D%E2%80%8C%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%8B_%E0%B0%93%E0%B0%A1%E0%B0%BF%E0%B0%A8_%E0%B0%A2%E0%B0%BF%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%80\" title=\"DC vs MI\u00a0 2023 : \u0c2e\u0c42\u0c21\u0c41 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b \u0c13\u0c21\u0c3f\u0c28 \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40\">DC vs MI\u00a0 2023 : \u0c2e\u0c42\u0c21\u0c41 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b \u0c13\u0c21\u0c3f\u0c28 \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E0%B0%A2%E0%B0%BF%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%80_%E0%B0%AF%E0%B1%8A%E0%B0%95%E0%B1%8D%E0%B0%95_%E0%B0%AC%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9F%E0%B1%8D%E0%B0%B8%E0%B1%8D%E2%80%8C%E0%B0%AE%E0%B0%A8%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%AC%E0%B1%8C%E0%B0%B2%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%86%E0%B0%B2%E0%B1%8D%E2%80%8C%E0%B0%B0%E0%B1%8C%E0%B0%82%E0%B0%A1%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D\" title=\"DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 : \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c28\u0c4d\u0c38\u0c4d, \u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c38\u0c4d, \u0c06\u0c32\u0c4d\u200c\u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d\u0c38\u0c4d\">DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 : \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c28\u0c4d\u0c38\u0c4d, \u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c38\u0c4d, \u0c06\u0c32\u0c4d\u200c\u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d\u0c38\u0c4d<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_2023_%E0%B0%A4%E0%B1%81%E0%B0%A6%E0%B0%BF_11_%E0%B0%AA%E0%B1%8D%E0%B0%B2%E0%B1%87%E0%B0%AF%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D\" title=\"DC vs MI 2023 : \u0c24\u0c41\u0c26\u0c3f 11 \u0c2a\u0c4d\u0c32\u0c47\u0c2f\u0c30\u0c4d\u0c38\u0c4d\">DC vs MI 2023 : \u0c24\u0c41\u0c26\u0c3f 11 \u0c2a\u0c4d\u0c32\u0c47\u0c2f\u0c30\u0c4d\u0c38\u0c4d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_2_%E0%B0%AE%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9A%E0%B1%8D%E2%80%8C%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%8B_%E0%B0%93%E0%B0%A1%E0%B0%BF%E0%B0%A8_%E0%B0%AE%E0%B1%81%E0%B0%82%E0%B0%AC%E0%B1%88\" title=\"DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 : 2 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b \u0c13\u0c21\u0c3f\u0c28 \u0c2e\u0c41\u0c02\u0c2c\u0c48\">DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 : 2 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b \u0c13\u0c21\u0c3f\u0c28 \u0c2e\u0c41\u0c02\u0c2c\u0c48<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E0%B0%AE%E0%B1%81%E0%B0%82%E0%B0%AC%E0%B1%88_%E0%B0%AC%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9F%E0%B1%8D%E0%B0%B8%E0%B1%8D%E2%80%8C%E0%B0%AE%E0%B0%A8%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%AC%E0%B1%8C%E0%B0%B2%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%86%E0%B0%B2%E0%B1%8D%E2%80%8C%E0%B0%B0%E0%B1%8C%E0%B0%82%E0%B0%A1%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D\" title=\"DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023: \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c28\u0c4d\u0c38\u0c4d, \u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c38\u0c4d, \u0c06\u0c32\u0c4d\u200c\u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d\u0c38\u0c4d\">DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023: \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c28\u0c4d\u0c38\u0c4d, \u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c38\u0c4d, \u0c06\u0c32\u0c4d\u200c\u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d\u0c38\u0c4d<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_2023_%E0%B0%A4%E0%B1%81%E0%B0%A6%E0%B0%BF_11_%E0%B0%AA%E0%B1%8D%E0%B0%B2%E0%B1%87%E0%B0%AF%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D-2\" title=\"DC vs MI 2023 : \u0c24\u0c41\u0c26\u0c3f 11 \u0c2a\u0c4d\u0c32\u0c47\u0c2f\u0c30\u0c4d\u0c38\u0c4d\">DC vs MI 2023 : \u0c24\u0c41\u0c26\u0c3f 11 \u0c2a\u0c4d\u0c32\u0c47\u0c2f\u0c30\u0c4d\u0c38\u0c4d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/blog.fun88inr.com\/te\/dc-vs-mi-prediction-2023-in-telugu\/#DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E2%80%93_2_%E0%B0%9C%E0%B0%9F%E0%B1%8D%E0%B0%B2_%E0%B0%B9%E0%B1%86%E0%B0%A1%E0%B1%8D_%E0%B0%9F%E0%B1%81_%E0%B0%B9%E0%B1%86%E0%B0%A1%E0%B1%8D_%E0%B0%AB%E0%B0%B2%E0%B0%BF%E0%B0%A4%E0%B0%BE%E0%B0%B2%E0%B1%81\" title=\"DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 &#8211; 2 \u0c1c\u0c1f\u0c4d\u0c32 \u0c39\u0c46\u0c21\u0c4d \u0c1f\u0c41 \u0c39\u0c46\u0c21\u0c4d \u0c2b\u0c32\u0c3f\u0c24\u0c3e\u0c32\u0c41\">DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 &#8211; 2 \u0c1c\u0c1f\u0c4d\u0c32 \u0c39\u0c46\u0c21\u0c4d \u0c1f\u0c41 \u0c39\u0c46\u0c21\u0c4d \u0c2b\u0c32\u0c3f\u0c24\u0c3e\u0c32\u0c41<\/a><\/li><\/ul><\/nav><\/div>\n<p><b>DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 (DC vs MI Prediction 2023) <\/b><span style=\"font-weight: 400;\">: \u0c08 \u0c38\u0c40\u0c1c\u0c28\u0c4d\u200c\u0c28\u0c41 \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c15\u0c4d\u0c2f\u0c3e\u0c2a\u0c3f\u0c1f\u0c32\u0c4d\u0c38\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c07\u0c02\u0c21\u0c3f\u0c2f\u0c28\u0c4d\u0c38\u0c4d \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c35\u0c3f\u0c27\u0c3e\u0c28\u0c02 \u0c28\u0c3f\u0c30\u0c3e\u0c36\u0c2a\u0c30\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c24\u0c28 \u0c30\u0c46\u0c02\u0c21\u0c41 \u0c13\u0c2a\u0c46\u0c28\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b\u0c28\u0c42 \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c17\u0c3e, \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c24\u0c4a\u0c32\u0c3f \u0c2e\u0c42\u0c21\u0c41 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b\u0c28\u0c42 \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c2f\u0c3f\u0c02\u0c26\u0c3f. \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c08 \u0c30\u0c46\u0c02\u0c21\u0c41 \u0c1c\u0c1f\u0c4d\u0c32\u0c41 \u0c2e\u0c41\u0c16\u0c3e\u0c2e\u0c41\u0c16\u0c3f \u0c24\u0c32\u0c2a\u0c21\u0c3f\u0c28\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c12\u0c15\u0c1f\u0c3f \u0c17\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c3f, \u0c2e\u0c30\u0c4a\u0c15\u0c1f\u0c3f \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c24\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f \u0c08 \u0c2a\u0c4b\u0c30\u0c41\u0c32\u0c4b \u0c0f \u0c1c\u0c1f\u0c4d\u0c1f\u0c41 \u0c17\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c4b \u0c1a\u0c42\u0c21\u0c3e\u0c32\u0c3f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E2%80%93_%E0%B0%AE%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9A%E0%B1%8D_%E0%B0%B5%E0%B0%BF%E0%B0%B5%E0%B0%B0%E0%B0%BE%E0%B0%B2%E0%B1%81\"><\/span><b>DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 &#8211; \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d \u0c35\u0c3f\u0c35\u0c30\u0c3e\u0c32\u0c41:<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c15\u0c4d\u0c2f\u0c3e\u0c2a\u0c3f\u0c1f\u0c32\u0c4d\u0c38\u0c4d Vs \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c07\u0c02\u0c21\u0c3f\u0c2f\u0c28\u0c4d\u0c38\u0c4d<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c35\u0c47\u0c26\u0c3f\u0c15: \u0c05\u0c30\u0c41\u0c23\u0c4d \u0c1c\u0c48\u0c1f\u0c4d\u0c32\u0c40 \u0c38\u0c4d\u0c1f\u0c47\u0c21\u0c3f\u0c2f\u0c02 (\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c24\u0c47\u0c26\u0c40 &amp; \u0c38\u0c2e\u0c2f\u0c02 : \u0c0f\u0c2a\u0c4d\u0c30\u0c3f\u0c32\u0c4d 11 &amp; 7:30 PM<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c32\u0c48\u0c35\u0c4d \u0c38\u0c4d\u0c1f\u0c4d\u0c30\u0c40\u0c2e\u0c3f\u0c02\u0c17\u0c4d: \u0c1c\u0c3f\u0c2f\u0c4b \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"DC_vs_MI_2023_%E0%B0%AE%E0%B1%82%E0%B0%A1%E0%B1%81_%E0%B0%AE%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9A%E0%B1%8D%E2%80%8C%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%8B_%E0%B0%93%E0%B0%A1%E0%B0%BF%E0%B0%A8_%E0%B0%A2%E0%B0%BF%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%80\"><\/span><b>DC vs MI\u00a0 2023 : \u0c2e\u0c42\u0c21\u0c41 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b \u0c13\u0c21\u0c3f\u0c28 \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c15\u0c4d\u0c2f\u0c3e\u0c2a\u0c3f\u0c1f\u0c32\u0c4d\u0c38\u0c4d \u0c38\u0c40\u0c1c\u0c28\u0c4d\u200c\u0c28\u0c41 \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c24\u0c40\u0c30\u0c41. \u0c30\u0c3e\u0c1c\u0c27\u0c3e\u0c28\u0c41\u0c32 \u0c15\u0c4b\u0c38\u0c02 \u0c30\u0c3e\u0c2c\u0c4b\u0c2f\u0c47 \u0c38\u0c2e\u0c2f\u0c02 \u0c1a\u0c3e\u0c32\u0c3e \u0c38\u0c35\u0c3e\u0c32\u0c41\u0c17\u0c3e \u0c09\u0c02\u0c1f\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c26\u0c3e\u0c28\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c1a\u0c3e\u0c32\u0c3e \u0c28\u0c3f\u0c30\u0c4d\u0c23\u0c2f\u0c3f\u0c02\u0c1a\u0c2c\u0c21\u0c3f\u0c02\u0c26\u0c3f. \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c1c\u0c1f\u0c4d\u0c1f\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f \u0c35\u0c30\u0c15\u0c41 \u0c06\u0c21\u0c3f\u0c28 \u0c2e\u0c42\u0c21\u0c41 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b\u0c28\u0c42 \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c2f\u0c3f\u0c02\u0c26\u0c3f. \u0c30\u0c3f\u0c37\u0c2c\u0c4d \u0c2a\u0c02\u0c24\u0c4d \u0c32\u0c47\u0c15\u0c2a\u0c4b\u0c35\u0c21\u0c02 \u0c21\u0c40\u0c38\u0c40\u0c28\u0c3f \u0c1a\u0c3e\u0c32\u0c3e \u0c2c\u0c3e\u0c27\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c06\u0c1f\u0c24\u0c40\u0c30\u0c41\u0c28\u0c41 \u0c1a\u0c42\u0c38\u0c4d\u0c24\u0c47\u0c28\u0c47 \u0c07\u0c26\u0c3f \u0c15\u0c28\u0c3f\u0c2a\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c3f. \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c46\u0c28\u0c4d\u200c\u0c32\u0c41 \u0c28\u0c21\u0c35\u0c32\u0c47\u0c30\u0c41 \u0c32\u0c47\u0c26\u0c3e \u0c35\u0c3e\u0c30\u0c3f \u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c32\u0c41 \u0c28\u0c21\u0c35\u0c32\u0c47\u0c30\u0c41. \u0c15\u0c46\u0c2a\u0c4d\u0c1f\u0c46\u0c28\u0c4d \u0c21\u0c47\u0c35\u0c3f\u0c21\u0c4d \u0c35\u0c3e\u0c30\u0c4d\u0c28\u0c30\u0c4d \u0c2a\u0c30\u0c41\u0c17\u0c41\u0c32\u0c41 \u0c1a\u0c47\u0c38\u0c3f\u0c28\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c15\u0c40 \u0c05\u0c24\u0c28\u0c3f \u0c38\u0c4d\u0c1f\u0c4d\u0c30\u0c48\u0c15\u0c4d \u0c30\u0c47\u0c1f\u0c4d \u0c1a\u0c3e\u0c32\u0c3e \u0c24\u0c15\u0c4d\u0c15\u0c41\u0c35\u0c17\u0c3e \u0c09\u0c02\u0c26\u0c3f. \u0c05\u0c24\u0c28\u0c41 \u0c24\u0c2a\u0c4d\u0c2a \u0c2e\u0c30\u0c47 \u0c07\u0c24\u0c30 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c46\u0c28\u0c4d \u0c15\u0c42\u0c21\u0c3e \u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f \u0c35\u0c30\u0c15\u0c41 \u0c28\u0c21\u0c35\u0c32\u0c47\u0c15\u0c2a\u0c4b\u0c2f\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c07\u0c02\u0c21\u0c3f\u0c2f\u0c28\u0c4d\u0c38\u0c4d\u200c\u0c2a\u0c48 \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c15\u0c4d\u0c2f\u0c3e\u0c2a\u0c3f\u0c1f\u0c32\u0c4d\u0c38\u0c4d \u0c1c\u0c1f\u0c4d\u0c1f\u0c41 \u0c0e\u0c32\u0c3e \u0c30\u0c3e\u0c23\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c4b \u0c1a\u0c42\u0c21\u0c3e\u0c32\u0c3f. \u0c15\u0c3e\u0c2c\u0c1f\u0c4d\u0c1f\u0c3f \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40\u0c15\u0c3f \u0c1a\u0c46\u0c02\u0c26\u0c3f\u0c28 \u0c15\u0c4a\u0c02\u0c24\u0c2e\u0c02\u0c26\u0c3f \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2e\u0c48\u0c28 \u0c06\u0c1f\u0c17\u0c3e\u0c33\u0c4d\u0c32\u0c28\u0c41 \u0c24\u0c46\u0c32\u0c41\u0c38\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3e\u0c02.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E0%B0%A2%E0%B0%BF%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%80_%E0%B0%AF%E0%B1%8A%E0%B0%95%E0%B1%8D%E0%B0%95_%E0%B0%AC%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9F%E0%B1%8D%E0%B0%B8%E0%B1%8D%E2%80%8C%E0%B0%AE%E0%B0%A8%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%AC%E0%B1%8C%E0%B0%B2%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%86%E0%B0%B2%E0%B1%8D%E2%80%8C%E0%B0%B0%E0%B1%8C%E0%B0%82%E0%B0%A1%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D\"><\/span><b>DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 : \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c28\u0c4d\u0c38\u0c4d, \u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c38\u0c4d, \u0c06\u0c32\u0c4d\u200c\u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d\u0c38\u0c4d<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table>\n<tbody>\n<tr>\n<td><b>\u0c06\u0c1f\u0c17\u0c3e\u0c21\u0c41<\/b><\/td>\n<td><b>\u0c30\u0c15\u0c02<\/b><\/td>\n<td><b>ipl \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u0c38\u0c4d<\/b><\/td>\n<td><b>\u0c2a\u0c30\u0c41\u0c17\u0c41\u0c32\u0c41<\/b><\/td>\n<td><b>\u0c35\u0c3f\u0c15\u0c46\u0c1f\u0c4d\u0c32\u0c41<\/b><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0c21\u0c47\u0c35\u0c3f\u0c21\u0c4d \u0c35\u0c3e\u0c30\u0c4d\u0c28\u0c30\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c3f\u0c02\u0c17\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">165<\/span><\/td>\n<td><span style=\"font-weight: 400;\">6039<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0c15\u0c41\u0c32\u0c4d\u0c26\u0c40\u0c2a\u0c4d \u0c2f\u0c3e\u0c26\u0c35\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c2c\u0c4c\u0c32\u0c30\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">62<\/span><\/td>\n<td><span style=\"font-weight: 400;\">115<\/span><\/td>\n<td><span style=\"font-weight: 400;\">63<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0c05\u0c15\u0c4d\u0c37\u0c30\u0c4d \u0c2a\u0c1f\u0c47\u0c32\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c06\u0c32\u0c4d \u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">125<\/span><\/td>\n<td><span style=\"font-weight: 400;\">1189<\/span><\/td>\n<td><span style=\"font-weight: 400;\">102<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><span class=\"ez-toc-section\" id=\"DC_vs_MI_2023_%E0%B0%A4%E0%B1%81%E0%B0%A6%E0%B0%BF_11_%E0%B0%AA%E0%B1%8D%E0%B0%B2%E0%B1%87%E0%B0%AF%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D\"><\/span><b style=\"font-family: NonBreakingSpaceOverride, 'Hoefler Text', Garamond, 'Times New Roman', serif; letter-spacing: normal;\">DC vs MI 2023 : \u0c24\u0c41\u0c26\u0c3f 11 \u0c2a\u0c4d\u0c32\u0c47\u0c2f\u0c30\u0c4d\u0c38\u0c4d<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c13\u0c2a\u0c46\u0c28\u0c30\u0c4d \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c30\u0c4d: \u0c21\u0c47\u0c35\u0c3f\u0c21\u0c4d \u0c35\u0c3e\u0c30\u0c4d\u0c28\u0c30\u0c4d (\u0c15\u0c46\u0c2a\u0c4d\u0c1f\u0c46\u0c28\u0c4d) \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c2a\u0c43\u0c25\u0c4d\u0c35\u0c40 \u0c37\u0c3e<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c2e\u0c3f\u0c21\u0c3f\u0c32\u0c4d \u0c06\u0c30\u0c4d\u0c21\u0c30\u0c4d: \u0c2e\u0c28\u0c40\u0c37\u0c4d \u0c2a\u0c3e\u0c02\u0c21\u0c47, \u0c30\u0c48\u0c32\u0c3f \u0c30\u0c4b\u0c38\u0c4b\u0c35\u0c4d, \u0c32\u0c32\u0c3f\u0c24\u0c4d \u0c2f\u0c3e\u0c26\u0c35\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c05\u0c15\u0c4d\u0c37\u0c30\u0c4d \u0c2a\u0c1f\u0c47\u0c32\u0c4d<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c32\u0c4b\u0c2f\u0c30\u0c4d \u0c06\u0c30\u0c4d\u0c21\u0c30\u0c4d: \u0c30\u0c4b\u0c35\u0c4d\u200c\u0c2e\u0c28\u0c4d \u0c2a\u0c3e\u0c35\u0c46\u0c32\u0c4d, \u0c38\u0c30\u0c4d\u0c2b\u0c30\u0c3e\u0c1c\u0c4d \u0c16\u0c3e\u0c28\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c05\u0c28\u0c4d\u0c30\u0c3f\u0c1a\u0c4d \u0c28\u0c3e\u0c30\u0c4d\u0c1f\u0c4d\u0c1c\u0c47<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c32\u0c41: \u0c15\u0c41\u0c32\u0c4d\u0c26\u0c40\u0c2a\u0c4d \u0c2f\u0c3e\u0c26\u0c35\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c1a\u0c47\u0c24\u0c28\u0c4d \u0c38\u0c15\u0c3e\u0c30\u0c3f\u0c2f\u0c3e<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_2_%E0%B0%AE%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9A%E0%B1%8D%E2%80%8C%E0%B0%B2%E0%B1%8D%E0%B0%B2%E0%B1%8B_%E0%B0%93%E0%B0%A1%E0%B0%BF%E0%B0%A8_%E0%B0%AE%E0%B1%81%E0%B0%82%E0%B0%AC%E0%B1%88\"><\/span><b>DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 : 2 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b \u0c13\u0c21\u0c3f\u0c28 \u0c2e\u0c41\u0c02\u0c2c\u0c48<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c07\u0c02\u0c21\u0c3f\u0c2f\u0c28\u0c4d\u0c38\u0c4d\u200c\u0c15\u0c41 \u0c10\u0c2a\u0c40\u0c0e\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c02\u0c32\u0c4b\u0c28\u0c47 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c41 \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c2f\u0c3e\u0c2f\u0c28\u0c3f \u0c1a\u0c46\u0c2c\u0c41\u0c24\u0c3e\u0c30\u0c41 \u0c15\u0c3e\u0c28\u0c40 \u0c08 \u0c38\u0c02\u0c35\u0c24\u0c4d\u0c38\u0c30\u0c02 \u0c35\u0c3e\u0c30\u0c41 \u0c2a\u0c4d\u0c30\u0c26\u0c30\u0c4d\u0c36\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c24\u0c40\u0c30\u0c41 \u0c2b\u0c3e\u0c28\u0c4d\u0c38\u0c4d\u200c\u0c28\u0c41 \u0c28\u0c3f\u0c30\u0c3e\u0c36\u0c2a\u0c30\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c26\u0c3e\u0c02\u0c24\u0c4b \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c05\u0c2d\u0c3f\u0c2e\u0c3e\u0c28\u0c41\u0c32\u0c41 \u0c15\u0c1a\u0c4d\u0c1a\u0c3f\u0c24\u0c02\u0c17\u0c3e \u0c06\u0c17\u0c4d\u0c30\u0c39\u0c02 \u0c35\u0c4d\u0c2f\u0c15\u0c4d\u0c24\u0c02 \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c24\u0c3f\u0c32\u0c15\u0c4d \u0c35\u0c30\u0c4d\u0c2e \u0c2e\u0c3f\u0c28\u0c39\u0c3e \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c46\u0c28\u0c4d \u0c0e\u0c35\u0c30\u0c42 \u0c30\u0c3e\u0c23\u0c3f\u0c02\u0c1a\u0c32\u0c47\u0c26\u0c41. \u0c30\u0c4b\u0c39\u0c3f\u0c24\u0c4d \u0c36\u0c30\u0c4d\u0c2e, \u0c07\u0c37\u0c3e\u0c28\u0c4d \u0c15\u0c3f\u0c37\u0c28\u0c4d \u0c1c\u0c1f\u0c4d\u0c1f\u0c41\u0c15\u0c41 \u0c36\u0c41\u0c2d\u0c3e\u0c30\u0c02\u0c2d\u0c02 \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c32\u0c47\u0c15\u0c2a\u0c4b\u0c17\u0c3e, \u0c2e\u0c3f\u0c21\u0c3f\u0c32\u0c3e\u0c30\u0c4d\u0c21\u0c30\u0c4d\u200c\u0c32\u0c4b \u0c38\u0c42\u0c30\u0c4d\u0c2f\u0c15\u0c41\u0c2e\u0c3e\u0c30\u0c4d \u0c2f\u0c3e\u0c26\u0c35\u0c4d \u0c2a\u0c4d\u0c30\u0c24\u0c4d\u0c2f\u0c47\u0c15\u0c02\u0c17\u0c3e \u0c0f\u0c2e\u0c40 \u0c1a\u0c47\u0c2f\u0c32\u0c47\u0c15\u0c2a\u0c4b\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c2c\u0c4c\u0c32\u0c3f\u0c02\u0c17\u0c4d \u0c17\u0c41\u0c30\u0c3f\u0c02\u0c1a\u0c3f \u0c1a\u0c46\u0c2a\u0c4d\u0c2a\u0c3e\u0c32\u0c02\u0c1f\u0c47, \u0c1c\u0c38\u0c4d\u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c2c\u0c41\u0c2e\u0c4d\u0c30\u0c3e \u0c32\u0c47\u0c15\u0c41\u0c02\u0c21\u0c3e, \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c07\u0c02\u0c21\u0c3f\u0c2f\u0c28\u0c4d\u0c38\u0c4d \u0c2c\u0c4c\u0c32\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c47\u0c32\u0c35\u0c02\u0c17\u0c3e \u0c15\u0c28\u0c3f\u0c2a\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c07\u0c15 \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40\u0c2a\u0c48 \u0c08 \u0c1c\u0c1f\u0c4d\u0c1f\u0c41 \u0c2a\u0c4d\u0c30\u0c26\u0c30\u0c4d\u0c36\u0c28 \u0c0e\u0c32\u0c3e \u0c09\u0c02\u0c1f\u0c41\u0c02\u0c26\u0c4b \u0c1a\u0c42\u0c21\u0c3e\u0c32\u0c3f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E0%B0%AE%E0%B1%81%E0%B0%82%E0%B0%AC%E0%B1%88_%E0%B0%AC%E0%B1%8D%E0%B0%AF%E0%B0%BE%E0%B0%9F%E0%B1%8D%E0%B0%B8%E0%B1%8D%E2%80%8C%E0%B0%AE%E0%B0%A8%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%AC%E0%B1%8C%E0%B0%B2%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D_%E0%B0%86%E0%B0%B2%E0%B1%8D%E2%80%8C%E0%B0%B0%E0%B1%8C%E0%B0%82%E0%B0%A1%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D\"><\/span><b>DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023: \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c4d\u0c38\u0c4d\u200c\u0c2e\u0c28\u0c4d\u0c38\u0c4d, \u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c38\u0c4d, \u0c06\u0c32\u0c4d\u200c\u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d\u0c38\u0c4d<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table>\n<tbody>\n<tr>\n<td><b>\u0c06\u0c1f\u0c17\u0c3e\u0c21\u0c41<\/b><\/td>\n<td><b>\u0c30\u0c15\u0c02<\/b><\/td>\n<td><b>ipl \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u0c38\u0c4d<\/b><\/td>\n<td><b>\u0c2a\u0c30\u0c41\u0c17\u0c41\u0c32\u0c41<\/b><\/td>\n<td><b>\u0c35\u0c3f\u0c15\u0c46\u0c1f\u0c4d\u0c32\u0c41<\/b><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0c30\u0c4b\u0c39\u0c3f\u0c24\u0c4d \u0c36\u0c30\u0c4d\u0c2e<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c3f\u0c02\u0c17\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">229<\/span><\/td>\n<td><span style=\"font-weight: 400;\">5901<\/span><\/td>\n<td><span style=\"font-weight: 400;\">15<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0c2a\u0c40\u0c2f\u0c42\u0c37\u0c4d \u0c1a\u0c3e\u0c35\u0c4d\u0c32\u0c3e<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c2c\u0c4c\u0c32\u0c30\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">166<\/span><\/td>\n<td><span style=\"font-weight: 400;\">589<\/span><\/td>\n<td><span style=\"font-weight: 400;\">158<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0c1c\u0c4b\u0c2b\u0c4d\u0c30\u0c3e \u0c06\u0c30\u0c4d\u0c1a\u0c30\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c06\u0c32\u0c4d \u0c30\u0c4c\u0c02\u0c21\u0c30\u0c4d<\/span><\/td>\n<td><span style=\"font-weight: 400;\">36<\/span><\/td>\n<td><span style=\"font-weight: 400;\">195<\/span><\/td>\n<td><span style=\"font-weight: 400;\">46<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><span class=\"ez-toc-section\" id=\"DC_vs_MI_2023_%E0%B0%A4%E0%B1%81%E0%B0%A6%E0%B0%BF_11_%E0%B0%AA%E0%B1%8D%E0%B0%B2%E0%B1%87%E0%B0%AF%E0%B0%B0%E0%B1%8D%E0%B0%B8%E0%B1%8D-2\"><\/span><b>DC vs MI 2023 : \u0c24\u0c41\u0c26\u0c3f 11 \u0c2a\u0c4d\u0c32\u0c47\u0c2f\u0c30\u0c4d\u0c38\u0c4d<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c13\u0c2a\u0c46\u0c28\u0c30\u0c4d \u0c2c\u0c4d\u0c2f\u0c3e\u0c1f\u0c30\u0c4d\u0c32\u0c41: \u0c30\u0c4b\u0c39\u0c3f\u0c24\u0c4d \u0c36\u0c30\u0c4d\u0c2e (\u0c15\u0c46\u0c2a\u0c4d\u0c1f\u0c46\u0c28\u0c4d), \u0c07\u0c37\u0c3e\u0c28\u0c4d \u0c15\u0c3f\u0c37\u0c28\u0c4d (\u0c35\u0c3f\u0c15\u0c46\u0c1f\u0c4d \u0c15\u0c40\u0c2a\u0c30\u0c4d)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c2e\u0c3f\u0c21\u0c3f\u0c32\u0c4d \u0c06\u0c30\u0c4d\u0c21\u0c30\u0c4d: \u0c38\u0c42\u0c30\u0c4d\u0c2f\u0c15\u0c41\u0c2e\u0c3e\u0c30\u0c4d \u0c2f\u0c3e\u0c26\u0c35\u0c4d, \u0c24\u0c3f\u0c32\u0c15\u0c4d \u0c35\u0c30\u0c4d\u0c2e \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c21\u0c46\u0c35\u0c3e\u0c32\u0c4d\u0c21\u0c4d \u0c2c\u0c4d\u0c30\u0c42\u0c2f\u0c3f\u0c38\u0c4d<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c32\u0c4b\u0c2f\u0c30\u0c4d \u0c06\u0c30\u0c4d\u0c21\u0c30\u0c4d: \u0c15\u0c3e\u0c2e\u0c46\u0c30\u0c3e\u0c28\u0c4d \u0c17\u0c4d\u0c30\u0c40\u0c28\u0c4d, \u0c1f\u0c3f\u0c2e\u0c4d \u0c21\u0c47\u0c35\u0c3f\u0c21\u0c4d\u0c38\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c1c\u0c4b\u0c2b\u0c4d\u0c30\u0c3e \u0c06\u0c30\u0c4d\u0c1a\u0c30\u0c4d<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0c2c\u0c4c\u0c32\u0c30\u0c4d\u0c32\u0c41: \u0c2a\u0c40\u0c2f\u0c42\u0c37\u0c4d \u0c1a\u0c3e\u0c35\u0c4d\u0c32\u0c3e, \u0c30\u0c3f\u0c1a\u0c30\u0c4d\u0c21\u0c4d\u200c\u0c38\u0c28\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c05\u0c30\u0c4d\u0c37\u0c26\u0c4d \u0c16\u0c3e\u0c28\u0c4d<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"DC_vs_MI_%E0%B0%AA%E0%B1%8D%E0%B0%B0%E0%B0%BF%E0%B0%A1%E0%B0%BF%E0%B0%95%E0%B1%8D%E0%B0%B7%E0%B0%A8%E0%B1%8D_2023_%E2%80%93_2_%E0%B0%9C%E0%B0%9F%E0%B1%8D%E0%B0%B2_%E0%B0%B9%E0%B1%86%E0%B0%A1%E0%B1%8D_%E0%B0%9F%E0%B1%81_%E0%B0%B9%E0%B1%86%E0%B0%A1%E0%B1%8D_%E0%B0%AB%E0%B0%B2%E0%B0%BF%E0%B0%A4%E0%B0%BE%E0%B0%B2%E0%B1%81\"><\/span><b>DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 &#8211; 2 \u0c1c\u0c1f\u0c4d\u0c32 \u0c39\u0c46\u0c21\u0c4d \u0c1f\u0c41 \u0c39\u0c46\u0c21\u0c4d \u0c2b\u0c32\u0c3f\u0c24\u0c3e\u0c32\u0c41<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c35\u0c30\u0c15\u0c41 \u0c06\u0c21\u0c3f\u0c28 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c32\u0c4b \u0c07\u0c30\u0c41 \u0c1c\u0c1f\u0c4d\u0c32\u0c41 \u0c12\u0c15\u0c26\u0c3e\u0c28\u0c3f\u0c2a\u0c48 \u0c0e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c3f\u0c1c\u0c2f\u0c3e\u0c32\u0c41 \u0c38\u0c3e\u0c27\u0c3f\u0c02\u0c1a\u0c3e\u0c2f\u0c28\u0c47\u0c26\u0c3f \u0c08 \u0c1f\u0c47\u0c2c\u0c41\u0c32\u0c4d \u0c26\u0c4d\u0c35\u0c3e\u0c30\u0c3e \u0c1a\u0c42\u0c21\u0c35\u0c1a\u0c4d\u0c1a\u0c41.<\/span><\/p>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0c06\u0c21\u0c3f\u0c28 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c41<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c17\u0c46\u0c32\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c17\u0c46\u0c32\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0c1f\u0c48<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">32<\/span><\/td>\n<td><span style=\"font-weight: 400;\">15<\/span><\/td>\n<td><span style=\"font-weight: 400;\">17<\/span><\/td>\n<td><span style=\"font-weight: 400;\">0<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-weight: 400;\">\u0c2e\u0c47\u0c2e\u0c41 \u0c30\u0c46\u0c02\u0c21\u0c41 \u0c1c\u0c1f\u0c4d\u0c32 \u0c17\u0c41\u0c30\u0c3f\u0c02\u0c1a\u0c3f \u0c2e\u0c3e\u0c1f\u0c4d\u0c32\u0c3e\u0c21\u0c3f\u0c28\u0c1f\u0c4d\u0c32\u0c2f\u0c3f\u0c24\u0c47, \u0c07\u0c26\u0c4d\u0c26\u0c30\u0c42 \u0c24\u0c2e \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c32\u0c4b \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c2f\u0c3e\u0c30\u0c41. \u0c15\u0c3e\u0c28\u0c40 \u0c30\u0c3f\u0c15\u0c3e\u0c30\u0c4d\u0c21\u0c41\u0c32\u0c28\u0c41 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c3f\u0c38\u0c4d\u0c24\u0c47 \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c2a\u0c1f\u0c3f\u0c37\u0c4d\u0c1f\u0c02\u0c17\u0c3e \u0c15\u0c28\u0c3f\u0c2a\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f \u0c15\u0c3e\u0c2c\u0c1f\u0c4d\u0c1f\u0c3f \u0c08 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4b \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c35\u0c3f\u0c1c\u0c2f\u0c02 \u0c38\u0c3e\u0c27\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c40\u0c30\u0c41 \u0c2a\u0c4d\u0c30\u0c24\u0c3f \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c15\u0c41 \u0c38\u0c02\u0c2c\u0c02\u0c27\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c15\u0c3e\u0c35\u0c3e\u0c32\u0c28\u0c41\u0c15\u0c41\u0c02\u0c1f\u0c47 <\/span><b><a href=\"https:\/\/blog.fun88inr.com\/te\/\">Fun88<\/a> <\/b><span style=\"font-weight: 400;\">\u0c2c\u0c4d\u0c32\u0c3e\u0c17\u0c4d \u0c1a\u0c42\u0c21\u0c02\u0c21\u0c3f. \u0c05\u0c32\u0c3e\u0c17\u0c47, \u0c15\u0c4d\u0c30\u0c3f\u0c15\u0c46\u0c1f\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c07\u0c24\u0c30 \u0c06\u0c1f\u0c32 \u0c2e\u0c40\u0c26 \u0c2c\u0c46\u0c1f\u0c4d\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c15\u0c4b\u0c38\u0c02 <\/span><a href=\"http:\/\/fun88inr.com\/in\"><b>Fun88 <\/b><\/a><span style=\"font-weight: 400;\">\u0c09\u0c24\u0c4d\u0c24\u0c2e\u0c2e\u0c48\u0c28\u0c26\u0c3f.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 (DC vs MI Prediction 2023) : \u0c08 \u0c38\u0c40\u0c1c\u0c28\u0c4d\u200c\u0c28\u0c41 \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c15\u0c4d\u0c2f\u0c3e\u0c2a\u0c3f\u0c1f\u0c32\u0c4d\u0c38\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c07\u0c02\u0c21\u0c3f\u0c2f\u0c28\u0c4d\u0c38\u0c4d \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c35\u0c3f\u0c27\u0c3e\u0c28\u0c02 \u0c28\u0c3f\u0c30\u0c3e\u0c36\u0c2a\u0c30\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c2e\u0c41\u0c02\u0c2c\u0c48 \u0c24\u0c28 \u0c30\u0c46\u0c02\u0c21\u0c41 \u0c13\u0c2a\u0c46\u0c28\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b\u0c28\u0c42 \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c17\u0c3e, \u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40 \u0c24\u0c4a\u0c32\u0c3f \u0c2e\u0c42\u0c21\u0c41 \u0c2e\u0c4d\u0c2f\u0c3e\u0c1a\u0c4d\u200c\u0c32\u0c4d\u0c32\u0c4b\u0c28\u0c42 \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c2f\u0c3f\u0c02\u0c26\u0c3f. \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c08 \u0c30\u0c46\u0c02\u0c21\u0c41 \u0c1c\u0c1f\u0c4d\u0c32\u0c41 \u0c2e\u0c41\u0c16\u0c3e\u0c2e\u0c41\u0c16\u0c3f \u0c24\u0c32\u0c2a\u0c21\u0c3f\u0c28\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c12\u0c15\u0c1f\u0c3f \u0c17\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c3f, \u0c2e\u0c30\u0c4a\u0c15\u0c1f\u0c3f \u0c13\u0c21\u0c3f\u0c2a\u0c4b\u0c24\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f \u0c08 \u0c2a\u0c4b\u0c30\u0c41\u0c32\u0c4b \u0c0f \u0c1c\u0c1f\u0c4d\u0c1f\u0c41 \u0c17\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c4b \u0c1a\u0c42\u0c21\u0c3e\u0c32\u0c3f. DC vs MI \u0c2a\u0c4d\u0c30\u0c3f\u0c21\u0c3f\u0c15\u0c4d\u0c37\u0c28\u0c4d 2023 &#8211; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":""},"categories":[4,6],"tags":[392],"_links":{"self":[{"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/posts\/2309"}],"collection":[{"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/comments?post=2309"}],"version-history":[{"count":1,"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/posts\/2309\/revisions"}],"predecessor-version":[{"id":2311,"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/posts\/2309\/revisions\/2311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/media\/2310"}],"wp:attachment":[{"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/media?parent=2309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/categories?post=2309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.fun88inr.com\/te\/wp-json\/wp\/v2\/tags?post=2309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}